{"id":14007,"date":"2018-06-04T16:31:44","date_gmt":"2018-06-04T15:31:44","guid":{"rendered":"http:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7.jpg"},"modified":"2018-06-04T16:36:55","modified_gmt":"2018-06-04T15:36:55","slug":"fresadora-sachman-7","status":"inherit","type":"attachment","link":"https:\/\/occasionmachines.com\/pt\/fresadora-sachman-de-mesa-apoiada\/fresadora-sachman-7\/","title":{"rendered":"Fresadora Sachman (7)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-14007","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7.jpg 700w, https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-416x278.jpg 416w, https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-768x512.jpg 768w, https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-550x367.jpg 550w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Fresadora SACHMAN de mesa apoiada <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":467,"file":"2018\/06\/Fresadora-Sachman-7.jpg","filesize":57215,"sizes":{"woocommerce_thumbnail":{"file":"Fresadora-Sachman-7-324x324.jpg","width":324,"height":324,"filesize":23493,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-324x324.jpg"},"woocommerce_gallery_thumbnail":{"file":"Fresadora-Sachman-7-100x100.jpg","width":100,"height":100,"filesize":4194,"mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-100x100.jpg"},"woocommerce_single":{"file":"Fresadora-Sachman-7-416x278.jpg","width":416,"height":278,"filesize":24438,"mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-416x278.jpg"},"thumbnail":{"file":"Fresadora-Sachman-7-74x74.jpg","width":"74","height":"74","mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-74x74.jpg"},"medium_large":{"file":"Fresadora-Sachman-7-768x512.jpg","width":"768","height":"512","mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-768x512.jpg"},"wptouch-new-thumbnail":{"file":"Fresadora-Sachman-7-144x144.jpg","width":"144","height":"144","mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-144x144.jpg"},"post-thumbnail":{"file":"Fresadora-Sachman-7-240x172.jpg","width":"240","height":"172","mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-240x172.jpg"},"shop_catalog":{"file":"Fresadora-Sachman-7-400x400.jpg","width":400,"height":400,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-400x400.jpg"},"shop_single":{"file":"Fresadora-Sachman-7-550x367.jpg","width":550,"height":367,"mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-550x367.jpg"},"shop_thumbnail":{"file":"Fresadora-Sachman-7-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7-100x100.jpg"},"full":{"file":"Fresadora-Sachman-7.jpg","width":700,"height":467,"mime_type":"image\/jpeg","source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":13996,"source_url":"https:\/\/occasionmachines.com\/wp-content\/uploads\/2018\/06\/Fresadora-Sachman-7.jpg","filename":"Fresadora-Sachman-7.jpg","filesize":57215,"_links":{"self":[{"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/media\/14007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/comments?post=14007"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":13996,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/posts\/13996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}