{"id":66981,"date":"2023-12-11T17:31:39","date_gmt":"2023-12-11T17:31:39","guid":{"rendered":"https:\/\/occasionmachines.com\/?post_type=product&#038;p=66981"},"modified":"2025-05-26T16:22:19","modified_gmt":"2025-05-26T15:22:19","slug":"maquina-retificadora-elb-swb8015-vaii","status":"publish","type":"product","link":"https:\/\/occasionmachines.com\/pt\/produto\/maquina-retificadora-elb-swb8015-vaii\/","title":{"rendered":"M\u00e1quina retificadora ELB SWB8015 VAII"},"content":{"rendered":"<p>Cursos<br \/>\n&#8211; Eixo X: 1500 mm<br \/>\n&#8211; Eixo Y: 500 mm<br \/>\n&#8211; Eixo Z: 500 mm<\/p>","protected":false},"excerpt":{"rendered":"<p>Cursos &#8211; Eixo X: 1500 mm &#8211; Eixo Y: 500 mm &#8211; Eixo Z: 500 mm<\/p>\n","protected":false},"featured_media":66994,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[7720,7722],"product_tag":[],"class_list":["post-66981","product","type-product","status-publish","has-post-thumbnail","product_cat-maquinas-usadas-e-recondicionadas","product_cat-retificadoras-usadas","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/product\/66981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/comments?post=66981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/media\/66994"}],"wp:attachment":[{"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/media?parent=66981"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/product_brand?post=66981"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/product_cat?post=66981"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/occasionmachines.com\/pt\/wp-json\/wp\/v2\/product_tag?post=66981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}